{"id":1878,"date":"2025-01-15T12:23:03","date_gmt":"2025-01-15T11:23:03","guid":{"rendered":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/?p=1878"},"modified":"2025-01-15T12:24:33","modified_gmt":"2025-01-15T11:24:33","slug":"programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme","status":"publish","type":"post","link":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/","title":{"rendered":"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l&rsquo;autisme"},"content":{"rendered":"<h3>Formation des Proches Aidants de personne ayant un <strong>TSA (Trouble du Spectre de l\u2019Autisme)<\/strong><\/h3>\n<p>anim\u00e9e par l&rsquo;<strong>IME Le Pr\u00e9lion<\/strong> sur l&rsquo;ann\u00e9e 2025, confi\u00e9 par le <strong>CRA-RA<\/strong> (<strong>Centre de Ressource Autisme Rh\u00f4ne-Alpes<\/strong> : <b><a href=\"https:\/\/www.cra-rhone-alpes.org\/\">site internet ici<\/a><\/b>).<\/p>\n<p>\ud83c\udfaf Objectif de cette formation : Apporter des \u00e9l\u00e9ments de compr\u00e9hension aux familles ainsi que des rep\u00e8res et outils pouvant les aider au quotidien.<\/p>\n<p>\ud83c\udfaf Objectif de cette formation : Permettre aux familles de prendre un r\u00f4le actif dans la prise en charge de leur enfant \/ adolescent \/ adulte gr\u00e2ce \u00e0 une sensibilisation et aux outils apport\u00e9s.<\/p>\n<p>\ud83c\udfaf Objectif de cette formation : Permettre aux familles d&rsquo;obenir du soutien en se rapprochant du r\u00e9seau d&rsquo;aide (<a href=\"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/nous-contacter\/\"><strong>Plateforme de r\u00e9pit <\/strong><\/a>et associations de parents)<\/p>\n<p>\ud83d\udc49 concerne toutes les familles r\u00e9sidant dans le <strong>d\u00e9partement de l\u2019Ain<\/strong>, que leur proche soit accompagn\u00e9 ou non par l\u2019<strong>ADAPEI de l\u2019Ain<\/strong>.<br \/>\n\ud83d\udc49 participation gratuite, possibilit\u00e9 de garde pour la personne avec TSA et sa fratrie.<\/p>\n<p><a href=\"http:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-content\/uploads\/2025\/01\/2025_FlyerFormationTSAPrelion.pdf\">\ud83d\udc49<b> Consulter la documentation en cliquant ici \ud83d\udc48<\/b><\/a><\/p>\n<h5>\ud83d\udcc514 dates r\u00e9parties dans l&rsquo;ann\u00e9e sur diff\u00e9rentes th\u00e9matiques dont :<\/h5>\n<p>&nbsp;<\/p>\n<p>\u00ab\u00a0Comprendre l&rsquo;autisme : de quoi parle-t-on ? \u00a0\u00bb le 10 janvier,<\/p>\n<p>\u00ab\u00a0Parcours d&rsquo;accompagnement et d\u00e9marches administratives\u00a0\u00bb le 14 f\u00e9vrier,<\/p>\n<p>\u00ab\u00a0TSA et sensorialit\u00e9\u00a0\u00bb le 21 mars,<\/p>\n<p>\u00ab\u00a0TSA et douleur\u00a0\u00bb le 11 avril,<\/p>\n<p>\u00ab\u00a0Education structur\u00e9e\u00a0\u00bb le 16 mai,<\/p>\n<p>\u00ab\u00a0La scolarisation de mon enfant TSA\u00a0\u00bb le 6 juin,<\/p>\n<p>\u00ab\u00a0Communication chez l&rsquo;enfant TSA le 27 juin\u00a0\u00bb,<\/p>\n<p>\u00ab\u00a0Comportements d\u00e9fis : comprendre et intervenir\u00a0\u00bb le 12 septembre,<\/p>\n<p>\u00ab\u00a0soins dentaires chez les personnes ayant un TSA\u00a0\u00bb le 26 septembre,<\/p>\n<p>\u00ab\u00a0Alimentation : quand manger devient tout un plat !\u00a0\u00bb le 10 septembre,<\/p>\n<p>\u00ab\u00a0Outils num\u00e9riques pour un quotidien plus facile\u00a0\u00bb le 7 novembre,<\/p>\n<p>\u00ab\u00a0Sexualit\u00e9 et autisme\u00a0\u00bb : cl\u00e9s de compr\u00e9hension\u00a0\u00bb le 28 novembre,<\/p>\n<p>\u00ab\u00a0Sommeil\u00a0\u00bb le 12 d\u00e9cembre<\/p>\n<p>et enfin, retour d&rsquo;exp\u00e9rience et \u00e9changes le 19 d\u00e9cembre 2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Formation des Proches Aidants de personne ayant un TSA (Trouble du Spectre de l\u2019Autisme) anim\u00e9e par l&rsquo;IME Le Pr\u00e9lion sur l&rsquo;ann\u00e9e 2025, confi\u00e9 par le CRA-RA (Centre de Ressource Autisme Rh\u00f4ne-Alpes : site internet ici). \ud83c\udfaf Objectif de cette formation : Apporter des \u00e9l\u00e9ments de compr\u00e9hension aux familles ainsi que des rep\u00e8res et outils pouvant<\/p>\n","protected":false},"author":4,"featured_media":1891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[139,144,40],"class_list":["post-1878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-au-quotidien","tag-139","tag-formation-aidants","tag-tsa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l&#039;autisme - PLATEFORME DE R\u00c9PIT DE L&#039;AIN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l&#039;autisme - PLATEFORME DE R\u00c9PIT DE L&#039;AIN\" \/>\n<meta property=\"og:description\" content=\"Formation des Proches Aidants de personne ayant un TSA (Trouble du Spectre de l\u2019Autisme) anim\u00e9e par l&rsquo;IME Le Pr\u00e9lion sur l&rsquo;ann\u00e9e 2025, confi\u00e9 par le CRA-RA (Centre de Ressource Autisme Rh\u00f4ne-Alpes : site internet ici). \ud83c\udfaf Objectif de cette formation : Apporter des \u00e9l\u00e9ments de compr\u00e9hension aux familles ainsi que des rep\u00e8res et outils pouvant\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/\" \/>\n<meta property=\"og:site_name\" content=\"PLATEFORME DE R\u00c9PIT DE L&#039;AIN\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-15T11:23:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-15T11:24:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-content\/uploads\/2025\/01\/ceremonie-trophees-APAJH-2024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ang\u00e9lique mermet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ang\u00e9lique mermet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/\"},\"author\":{\"name\":\"ang\u00e9lique mermet\",\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/#\\\/schema\\\/person\\\/90be931d8332ca958c286bc229ccccd1\"},\"headline\":\"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l&rsquo;autisme\",\"datePublished\":\"2025-01-15T11:23:03+00:00\",\"dateModified\":\"2025-01-15T11:24:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/\"},\"wordCount\":308,\"image\":{\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/ceremonie-trophees-APAJH-2024.png\",\"keywords\":[\"2025\",\"formation aidants\",\"TSA\"],\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/\",\"url\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/\",\"name\":\"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l'autisme - PLATEFORME DE R\u00c9PIT DE L&#039;AIN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/ceremonie-trophees-APAJH-2024.png\",\"datePublished\":\"2025-01-15T11:23:03+00:00\",\"dateModified\":\"2025-01-15T11:24:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/#\\\/schema\\\/person\\\/90be931d8332ca958c286bc229ccccd1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/ceremonie-trophees-APAJH-2024.png\",\"contentUrl\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/ceremonie-trophees-APAJH-2024.png\",\"width\":1640,\"height\":924},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l&rsquo;autisme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/#website\",\"url\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/\",\"name\":\"PLATEFORME DE R\u00c9PIT DE L&#039;AIN\",\"description\":\"APAJH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/#\\\/schema\\\/person\\\/90be931d8332ca958c286bc229ccccd1\",\"name\":\"ang\u00e9lique mermet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e936eb366bedac64025cc82a6ff20ca2855575c1b2d689e99a6872a8ed13cf35?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e936eb366bedac64025cc82a6ff20ca2855575c1b2d689e99a6872a8ed13cf35?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e936eb366bedac64025cc82a6ff20ca2855575c1b2d689e99a6872a8ed13cf35?s=96&d=mm&r=g\",\"caption\":\"ang\u00e9lique mermet\"},\"url\":\"https:\\\/\\\/apajhetvous.apajh.org\\\/plateformederepitdelain\\\/author\\\/amermet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l'autisme - PLATEFORME DE R\u00c9PIT DE L&#039;AIN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/","og_locale":"fr_FR","og_type":"article","og_title":"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l'autisme - PLATEFORME DE R\u00c9PIT DE L&#039;AIN","og_description":"Formation des Proches Aidants de personne ayant un TSA (Trouble du Spectre de l\u2019Autisme) anim\u00e9e par l&rsquo;IME Le Pr\u00e9lion sur l&rsquo;ann\u00e9e 2025, confi\u00e9 par le CRA-RA (Centre de Ressource Autisme Rh\u00f4ne-Alpes : site internet ici). \ud83c\udfaf Objectif de cette formation : Apporter des \u00e9l\u00e9ments de compr\u00e9hension aux familles ainsi que des rep\u00e8res et outils pouvant","og_url":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/","og_site_name":"PLATEFORME DE R\u00c9PIT DE L&#039;AIN","article_published_time":"2025-01-15T11:23:03+00:00","article_modified_time":"2025-01-15T11:24:33+00:00","og_image":[{"width":1640,"height":924,"url":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-content\/uploads\/2025\/01\/ceremonie-trophees-APAJH-2024.png","type":"image\/png"}],"author":"ang\u00e9lique mermet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ang\u00e9lique mermet","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/#article","isPartOf":{"@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/"},"author":{"name":"ang\u00e9lique mermet","@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/#\/schema\/person\/90be931d8332ca958c286bc229ccccd1"},"headline":"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l&rsquo;autisme","datePublished":"2025-01-15T11:23:03+00:00","dateModified":"2025-01-15T11:24:33+00:00","mainEntityOfPage":{"@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/"},"wordCount":308,"image":{"@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/#primaryimage"},"thumbnailUrl":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-content\/uploads\/2025\/01\/ceremonie-trophees-APAJH-2024.png","keywords":["2025","formation aidants","TSA"],"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/","url":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/","name":"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l'autisme - PLATEFORME DE R\u00c9PIT DE L&#039;AIN","isPartOf":{"@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/#primaryimage"},"image":{"@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/#primaryimage"},"thumbnailUrl":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-content\/uploads\/2025\/01\/ceremonie-trophees-APAJH-2024.png","datePublished":"2025-01-15T11:23:03+00:00","dateModified":"2025-01-15T11:24:33+00:00","author":{"@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/#\/schema\/person\/90be931d8332ca958c286bc229ccccd1"},"breadcrumb":{"@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/#primaryimage","url":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-content\/uploads\/2025\/01\/ceremonie-trophees-APAJH-2024.png","contentUrl":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-content\/uploads\/2025\/01\/ceremonie-trophees-APAJH-2024.png","width":1640,"height":924},{"@type":"BreadcrumbList","@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/programme-2025-formation-des-proches-aidants-de-personne-ayant-un-trouble-du-spectre-de-lautisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/"},{"@type":"ListItem","position":2,"name":"Programme 2025 formation des proches aidants de personne ayant un trouble du spectre de l&rsquo;autisme"}]},{"@type":"WebSite","@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/#website","url":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/","name":"PLATEFORME DE R\u00c9PIT DE L&#039;AIN","description":"APAJH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/#\/schema\/person\/90be931d8332ca958c286bc229ccccd1","name":"ang\u00e9lique mermet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e936eb366bedac64025cc82a6ff20ca2855575c1b2d689e99a6872a8ed13cf35?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e936eb366bedac64025cc82a6ff20ca2855575c1b2d689e99a6872a8ed13cf35?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e936eb366bedac64025cc82a6ff20ca2855575c1b2d689e99a6872a8ed13cf35?s=96&d=mm&r=g","caption":"ang\u00e9lique mermet"},"url":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/author\/amermet\/"}]}},"_links":{"self":[{"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/posts\/1878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/comments?post=1878"}],"version-history":[{"count":13,"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/posts\/1878\/revisions"}],"predecessor-version":[{"id":1895,"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/posts\/1878\/revisions\/1895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/media\/1891"}],"wp:attachment":[{"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/media?parent=1878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/categories?post=1878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apajhetvous.apajh.org\/plateformederepitdelain\/wp-json\/wp\/v2\/tags?post=1878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}